{"id":238,"count":5,"description":"","link":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/","name":"Europe Atlantic Coast","slug":"atlantic-coast","taxonomy":"category","parent":1,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europe Atlantic Coast Archives - Tranquility Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europe Atlantic Coast Archives - Tranquility Mare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/\" \/>\n<meta property=\"og:site_name\" content=\"Tranquility Mare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tranquilitymare.com\\\/en\\\/category\\\/sailing\\\/atlantic-coast\\\/\",\"url\":\"https:\\\/\\\/tranquilitymare.com\\\/en\\\/category\\\/sailing\\\/atlantic-coast\\\/\",\"name\":\"Europe Atlantic Coast Archives - Tranquility Mare\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tranquilitymare.com\\\/en\\\/category\\\/sailing\\\/atlantic-coast\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tranquilitymare.com\\\/en\\\/category\\\/sailing\\\/atlantic-coast\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tranquilitymare.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sailing\",\"item\":\"https:\\\/\\\/tranquilitymare.com\\\/category\\\/sailing\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Europe Atlantic Coast\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/\",\"name\":\"Tranquility Mare\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/#\\\/schema\\\/person\\\/149bd3e07d45664e76be454f3ce97c37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/tranquilitymare.com\\\/en\\\/#\\\/schema\\\/person\\\/149bd3e07d45664e76be454f3ce97c37\",\"name\":\"tranquilitymare.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tranquilitymare.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-corfu-4433-scaled-2.jpg\",\"url\":\"https:\\\/\\\/tranquilitymare.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-corfu-4433-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/tranquilitymare.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-corfu-4433-scaled-2.jpg\",\"width\":2556,\"height\":1195,\"caption\":\"tranquilitymare.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/tranquilitymare.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-corfu-4433-scaled-2.jpg\"},\"sameAs\":[\"http:\\\/\\\/tranquilitymare.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europe Atlantic Coast Archives - Tranquility Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/","og_locale":"en_GB","og_type":"article","og_title":"Europe Atlantic Coast Archives - Tranquility Mare","og_url":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/","og_site_name":"Tranquility Mare","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/","url":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/","name":"Europe Atlantic Coast Archives - Tranquility Mare","isPartOf":{"@id":"http:\/\/tranquilitymare.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/tranquilitymare.com\/en\/category\/sailing\/atlantic-coast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tranquilitymare.com\/"},{"@type":"ListItem","position":2,"name":"Sailing","item":"https:\/\/tranquilitymare.com\/category\/sailing\/"},{"@type":"ListItem","position":3,"name":"Europe Atlantic Coast"}]},{"@type":"WebSite","@id":"http:\/\/tranquilitymare.com\/en\/#website","url":"http:\/\/tranquilitymare.com\/en\/","name":"Tranquility Mare","description":"","publisher":{"@id":"http:\/\/tranquilitymare.com\/en\/#\/schema\/person\/149bd3e07d45664e76be454f3ce97c37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/tranquilitymare.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"http:\/\/tranquilitymare.com\/en\/#\/schema\/person\/149bd3e07d45664e76be454f3ce97c37","name":"tranquilitymare.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tranquilitymare.com\/wp-content\/uploads\/2023\/12\/cropped-corfu-4433-scaled-2.jpg","url":"https:\/\/tranquilitymare.com\/wp-content\/uploads\/2023\/12\/cropped-corfu-4433-scaled-2.jpg","contentUrl":"https:\/\/tranquilitymare.com\/wp-content\/uploads\/2023\/12\/cropped-corfu-4433-scaled-2.jpg","width":2556,"height":1195,"caption":"tranquilitymare.com"},"logo":{"@id":"https:\/\/tranquilitymare.com\/wp-content\/uploads\/2023\/12\/cropped-corfu-4433-scaled-2.jpg"},"sameAs":["http:\/\/tranquilitymare.com"]}]}},"_links":{"self":[{"href":"https:\/\/tranquilitymare.com\/en\/wp-json\/wp\/v2\/categories\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tranquilitymare.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tranquilitymare.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/tranquilitymare.com\/en\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/tranquilitymare.com\/en\/wp-json\/wp\/v2\/posts?categories=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}